{"id":1998,"date":"2020-11-06T16:49:13","date_gmt":"2020-11-06T15:49:13","guid":{"rendered":"https:\/\/nauivanow.com\/nota-legal\/"},"modified":"2021-05-10T11:10:37","modified_gmt":"2021-05-10T10:10:37","slug":"nota-legal","status":"publish","type":"page","link":"https:\/\/nauivanow.com\/es\/nota-legal\/","title":{"rendered":"Nota legal"},"content":{"rendered":"<div class=\"wp-block heading h6 body-block page-container \">\n<h6 class=\"wp-block-heading\"><strong>1. INFORMACI\u00d3N GENERAL<\/strong><\/h6>\n<\/div>\n\n<div class=\"wp-block body-block paragraph page-container\">\n<p class=\"wp-block-paragraph\">La Fundaci\u00f3 Privada Sagrera es una fundaci\u00f3n privada constituida el 12 de enero de 2006 que tiene el objeto de facilitar la creaci\u00f3n, la difusi\u00f3n y la capacitaci\u00f3n de los profesionales de la cultura y las artes esc\u00e9nicas, en especial del teatro, con una atenci\u00f3n especial hacia los nuevos creadores.<\/p>\n<\/div>\n\n<div class=\"wp-block body-block paragraph page-container\">\n<p class=\"wp-block-paragraph\">La Fundaci\u00f3 Privada Sagrera (en adelante, referida como Fundaci\u00f3) fue inscrita en el Registro de Fundaciones Privadas de la Generalitat de Catalu\u00f1a, en virtud de la orden del Consejo de Justicia de 29\/XII\/1988, con n\u00famero 2.192 y tiene su domicilio social en la calle Hondures, 28-30, bajos, de Barcelona (08027) y el CIF G64112303.<\/p>\n<\/div>\n\n<div class=\"wp-block heading h6 body-block page-container \">\n<h6 class=\"wp-block-heading\"><br><strong>2. OBJETO<\/strong><\/h6>\n<\/div>\n\n<div class=\"wp-block body-block paragraph page-container\">\n<p class=\"wp-block-paragraph\">La p\u00e1gina web&nbsp;www.nauivanow.com, propiedad de la Fundaci\u00f3, ha sido creada y dise\u00f1ada para dar a conocer y permitir el acceso general de todos los usuarios de internet, a la informaci\u00f3n, actividades, productos y servicios diversos, propios o de terceros, ofrecidos por la Nau Ivanow.<\/p>\n<\/div>\n\n<div class=\"wp-block body-block paragraph page-container\">\n<p class=\"wp-block-paragraph\">La presente Nota legal tiene como objeto establecer las condiciones generales que regulan el acceso y uso general de esta p\u00e1gina web por parte de todos los usuarios, de forma que, el acceso y su uso suponen la sumisi\u00f3n y la aceptaci\u00f3n de las condiciones generales incluidas en esta Nota legal.<\/p>\n<\/div>\n\n<div class=\"wp-block body-block paragraph page-container\">\n<p class=\"wp-block-paragraph\">La Fundaci\u00f3 se reserva la facultad de realizar, en cualquier momento y sin necesidad de ning\u00fan preaviso, cualquier modificaci\u00f3n o actualizaci\u00f3n de los contenidos y servicios, de las disposiciones de esta Nota legal&nbsp;y, en general, de todos los elementos que integren el dise\u00f1o y la configuraci\u00f3n de su p\u00e1gina web.<\/p>\n<\/div>\n\n<div class=\"wp-block heading h6 body-block page-container \">\n<h6 class=\"wp-block-heading\"><br><strong>3. ACCESO Y USO DE LA P\u00c1GINA WEB<\/strong><\/h6>\n<\/div>\n\n<div class=\"wp-block body-block paragraph page-container\">\n<p class=\"wp-block-paragraph\"><strong>3.1. Acceso a la p\u00e1gina web<\/strong><br>Los usuarios pueden acceder de forma gratuita y libre a la p\u00e1gina web. En caso de que haya productos o servicios que requieran un determinado pago, la Fundaci\u00f3 informar\u00e1 de las condiciones particulares correspondientes a los usuarios.<\/p>\n<\/div>\n\n<div class=\"wp-block body-block paragraph page-container\">\n<p class=\"wp-block-paragraph\">En general, el acceso a la informaci\u00f3n y a las utilidades de esta p\u00e1gina web no exige registro previo de usuario. No obstante, los usuarios podr\u00e1n solicitar, cumplimentando los formularios correspondientes, la recepci\u00f3n de informaci\u00f3n y publicidad sobre la Fundaci\u00f3 (bolet\u00edn informativo, etc). Los usuarios garantizan que toda la informaci\u00f3n y los datos de car\u00e1cter personal facilitados en los formularios ser\u00e1n propios y ciertos. Los usuarios ser\u00e1n los \u00fanicos responsables de las manifestaciones falsas o inexactas que hagan, y de los perjuicios que el uso de esta informaci\u00f3n pueda ocasionar a la Fundaci\u00f3 o a terceros. Igualmente, los usuarios se comprometen a notificar a la Fundaci\u00f3 cualquier cambio que se pueda producir, en relaci\u00f3n a la informaci\u00f3n y a los datos personales comunicados.<\/p>\n<\/div>\n\n<div class=\"wp-block body-block paragraph page-container\">\n<p class=\"wp-block-paragraph\">La Fundaci\u00f3 se reserva el derecho a interrumpir el acceso a su p\u00e1gina web, en cualquier momento y sin previo aviso, ya sea por motivos de seguridad, de control, de mantenimiento, por errores de suministro el\u00e9ctrico o por cualquier otra causa. Esta interrupci\u00f3n podr\u00e1 tener car\u00e1cter temporal o definitivo, en cuyo caso se comunicar\u00e1 a los usuarios. En consecuencia, la Fundaci\u00f3 no garantiza la fiabilidad, la disponibilidad ni la continuidad de su p\u00e1gina web, en el supuesto de que se presenten las causas anteriormente mencionadas, y, por lo tanto, en ning\u00fan momento se podr\u00e1n exigir responsabilidades a la Fundaci\u00f3 en este sentido.<\/p>\n<\/div>\n\n<div class=\"wp-block body-block paragraph page-container\">\n<p class=\"wp-block-paragraph\"><strong>3.2. Uso de la p\u00e1gina web<\/strong><br>La utilizaci\u00f3n de la p\u00e1gina web de la Fundaci\u00f3 por cualquier persona le atribuye la condici\u00f3n de usuario, quien acepta que lo usa bajo su exclusiva responsabilidad.<\/p>\n<\/div>\n\n<div class=\"wp-block body-block paragraph page-container\">\n<p class=\"wp-block-paragraph\">Los usuarios se comprometen a utilizar informaci\u00f3n, actividades, productos o servicios que la Fundaci\u00f3 pone a su disposici\u00f3n en esta p\u00e1gina web conforme a las presentes condiciones generales y a la legalidad vigente, y, en todo caso, se compromete a no utilizarlo para actividades contrarias a las leyes, a la moral o al orden p\u00fablico.<\/p>\n<\/div>\n\n<div class=\"wp-block body-block paragraph page-container\">\n<p class=\"wp-block-paragraph\">Los usuarios pueden descargar los contenidos que deseen de la p\u00e1gina web y, cuando sea necesario, la Fundaci\u00f3 informar\u00e1 al usuario sobre las especificaciones t\u00e9cnicas necesarias para proceder a la descarga de informaci\u00f3n y contenidos de su p\u00e1gina web. En este sentido, los usuarios se tendr\u00e1n que abstener de obtener, o intentar obtener, los contenidos de esta p\u00e1gina web por medios o procedimientos distintos de los que en cada caso se hayan puesto a su disposici\u00f3n o hayan indicado al efecto, o de los que se utilicen habitualmente en internet.<\/p>\n<\/div>\n\n<div class=\"wp-block body-block paragraph page-container\">\n<p class=\"wp-block-paragraph\">Los contenidos de la p\u00e1gina web son puestos a disposici\u00f3n de los usuarios por la Fundaci\u00f3 como informaci\u00f3n propia o, en su caso, de terceros. De este modo, la Fundaci\u00f3 pondr\u00e1 a su disposici\u00f3n los medios razonables para que los contenidos incluidos en su p\u00e1gina web sean exactos y est\u00e9n actualizados. <\/p>\n<\/div>\n\n<div class=\"wp-block body-block paragraph page-container\">\n<p class=\"wp-block-paragraph\">En cuanto a los menores de edad que quieran hacer uso de esta p\u00e1gina web, deber\u00e1n tener el permiso de sus padres o tutores, que en todo caso ser\u00e1n los responsables de sus actos. No obstante, la Fundaci\u00f3 garantiza la protecci\u00f3n del menor en cuanto a los contenidos dirigidos especialmente al p\u00fablico familiar.<\/p>\n<\/div>\n\n<div class=\"wp-block body-block paragraph page-container\">\n<p class=\"wp-block-paragraph\"><br><strong>4. PROPIEDAD INDUSTRIAL E INTELECTUAL<\/strong><br><br><strong>4.1. Contenidos<\/strong><br>Todos los contenidos de esta p\u00e1gina web, entendiendo como tales, a t\u00edtulo meramente enunciativo, textos, fotograf\u00edas, gr\u00e1ficos, im\u00e1genes, iconos, signos distintivos o logotipos, marcas, nombres comerciales, tecnolog\u00eda, software, enlaces y otros contenidos audiovisuales o sonoros, as\u00ed como su dise\u00f1o gr\u00e1fico y c\u00f3digos fuente (referidos de forma abreviada como los \u2018Contenidos\u2019), son propiedad intelectual de la Fundaci\u00f3 o, en su caso, de terceros, salvo que se especifique lo contrario.<\/p>\n<\/div>\n\n<div class=\"wp-block body-block paragraph page-container\">\n<p class=\"wp-block-paragraph\">Los usuarios deber\u00e1n respetar en todo momento todos los derechos de propiedad intelectual e industrial sobre esta p\u00e1gina web, de titularidad de la Fundaci\u00f3 o de terceros.<\/p>\n<\/div>\n\n<div class=\"wp-block body-block paragraph page-container\">\n<p class=\"wp-block-paragraph\">Queda expresamente prohibida la reproducci\u00f3n, transformaci\u00f3n, distribuci\u00f3n, comunicaci\u00f3n p\u00fablica, puesta a disposici\u00f3n, extracci\u00f3n, reutilizaci\u00f3n, retransmisi\u00f3n o utilizaci\u00f3n de cualquier naturaleza, por cualquier medio o procedimiento, de cualquiera de estos derechos, exceptuando los casos en los que est\u00e9 legalmente permitido, es decir, autorizado por el titular de los correspondientes derechos. Para la utilizaci\u00f3n autorizada de los contenidos de esta p\u00e1gina web, con fines exclusivamente informativos o pedag\u00f3gicos, los usuarios pueden dirigirse a <a href=\"mailto:info@nauivanow.com\" target=\"_blank\" rel=\"noreferrer noopener\">info@nauivanow.com<\/a>.<\/p>\n<\/div>\n\n<div class=\"wp-block body-block paragraph page-container\">\n<p class=\"wp-block-paragraph\">No obstante el p\u00e1rrafo anterior, los usuarios podr\u00e1n visualizar y obtener una copia privada temporal de los contenidos para su exclusivo uso personal y privado en sus sistemas inform\u00e1ticos (software y hardware), siempre que no sea con el fin de desarrollar actividades de car\u00e1cter comercial o profesional o con fines de distribuci\u00f3n, modificaci\u00f3n, alteraci\u00f3n o descompilaci\u00f3n.<\/p>\n<\/div>\n\n<div class=\"wp-block body-block paragraph page-container\">\n<p class=\"wp-block-paragraph\"><strong>4.2. Enlaces desde esta p\u00e1gina web<\/strong><br>Los enlaces de esta p\u00e1gina web a p\u00e1ginas web de terceros se suministran exclusivamente como una utilidad para los usuarios, que al utilizar estos enlaces salen de la p\u00e1gina web la Fundaci\u00f3. Por lo tanto, el uso de estos enlaces lleva a los usuarios a p\u00e1ginas web de las cuales la Fundaci\u00f3 no es titular ni en ning\u00fan caso responsable jur\u00eddico.<\/p>\n<\/div>\n\n<div class=\"wp-block body-block paragraph page-container\">\n<p class=\"wp-block-paragraph\"><br><strong>5. RESPONSABILIDADES<\/strong><br><br>Los usuarios responder\u00e1n de los da\u00f1os y perjuicios de cualquier naturaleza que la Fundaci\u00f3 o terceros puedan sufrir como consecuencia del incumplimiento de cualquiera de las disposiciones estipuladas en esta Nota legal o, en su caso, en las condiciones particulares que sean de aplicaci\u00f3n.<\/p>\n<\/div>\n\n<div class=\"wp-block body-block paragraph page-container\">\n<p class=\"wp-block-paragraph\">La Fundaci\u00f3 no se responsabiliza de los da\u00f1os y perjuicios producidos en los equipos inform\u00e1ticos de los usuarios o de terceros derivados del acceso a esta p\u00e1gina web, dado que este acceso no supone en ning\u00fan caso la obligaci\u00f3n de la Fundaci\u00f3 de controlar la ausencia de virus, gusanos o cualquier otro elemento inform\u00e1tico da\u00f1oso.<\/p>\n<\/div>\n\n<div class=\"wp-block body-block paragraph page-container\">\n<p class=\"wp-block-paragraph\">La Fundaci\u00f3 no se responsabiliza de los contenidos y servicios de los enlaces, p\u00e1ginas o sistemas de terceros conectados a esta p\u00e1gina web y, por lo tanto, no se hace responsable de los da\u00f1os producidos por la ilicitud, calidad, desactualitzaci\u00f3n, indisponibilidad, error o inutilidad de los mismos.<\/p>\n<\/div>\n\n<div class=\"wp-block body-block paragraph page-container\">\n<p class=\"wp-block-paragraph\"><br><strong>6. POL\u00cdTICA DE PRIVACIDAD<\/strong><\/p>\n<\/div>\n\n<div class=\"wp-block body-block paragraph page-container\">\n<p class=\"wp-block-paragraph\"><strong>6.1. Responsable del tratamiento de datos<\/strong><\/p>\n<\/div>\n\n<div class=\"wp-block body-block list page-container\">\n<ul class=\"wp-block-list\"><li><strong>Identidad<\/strong>:&nbsp;Fundaci\u00f3 Privada Sagrera \u2013 Nau Ivanow, en adelante Fundaci\u00f3<\/li><li><strong>CIF<\/strong>:&nbsp;G64112303<br>Inscrita en el Registro de Fundaciones Privadas de la Generalitat de Catalu\u00f1a, en virtud de la orden del Consejo de Justicia de 29\/XII\/1988, con n\u00famero 2.192.<\/li><li><strong>Direcci\u00f3n<\/strong>:&nbsp;C. Hondures, 28-30, bajos, de Barcelona 08027<\/li><li><strong>Tel\u00e9fono<\/strong>: 93 340 74 68<\/li><li><strong>Correo electr\u00f3nico<\/strong>:&nbsp;info@nauivanow.com<\/li><li><strong>Delegado de Protecci\u00f3n de Datos<\/strong>: &nbsp;Fundaci\u00f3 Privada Sagrera,&nbsp;<a href=\"mailto:info@nauivanow.com\">info@nauivanow.com<\/a><\/li><\/ul>\n<\/div>\n\n<div class=\"wp-block body-block paragraph page-container\">\n<p class=\"wp-block-paragraph\">La Fundaci\u00f3, como responsable del sitio web, en conformidad con lo que dispone el Reglamento (UE) 2016\/679 de 27 de abril de 2016 (RGPD) relativo a la protecci\u00f3n de las personas f\u00edsicas en cuanto al tratamiento de datos personales, y por la Ley 34\/2002, de 11 de julio, de Servicios de la Sociedad de la Informaci\u00f3n y del Comercio Electr\u00f3nico <em>(<\/em>LSSICE), informa que tiene implementadas las medidas de seguridad necesarias, de \u00edndole t\u00e9cnica y organizativas, para garantizar y proteger la confidencialidad, integridad y disponibilidad de los datos introducidos.<\/p>\n<\/div>\n\n<div class=\"wp-block body-block paragraph page-container\">\n<p class=\"wp-block-paragraph\"><strong>6.2. Finalidad del <strong>tratamiento<\/strong><\/strong><br>Sus datos personales solo se utilizar\u00e1n para las siguientes finalidades:<\/p>\n<\/div>\n\n<div class=\"wp-block body-block list page-container\">\n<ul class=\"wp-block-list\"><li>Realizar las gestiones comerciales y administrativas necesarias con los usuarios de la web.<\/li><li>Enviar comunicaciones comerciales publicitarias y promocionales, en caso de que el usuario haya consentido expresamente el env\u00edo de comunicaciones comerciales por v\u00eda electr\u00f3nica mediante la suscripci\u00f3n al bolet\u00edn.<\/li><li>Responder a las consultas y\/o proporcionar informaciones requeridas por el usuario.<\/li><li>Realizar las prestaciones de servicios y\/o productos contratados o subscritos por el usuario.<\/li><li>Utilizar sus datos para contactarle, tanto por v\u00eda electr\u00f3nica como no electr\u00f3nica, para obtener su opini\u00f3n sobre el servicio prestado.<\/li><li>Notificarle cambios, desarrollos importantes de la pol\u00edtica de privacidad, nota legal o pol\u00edtica de <em>cookies<\/em>.<\/li><li>Los datos de clientes y\/o de proveedores ser\u00e1n tratados, dentro de la relaci\u00f3n contractual que los vincula con el responsable, en cumplimiento de las obligaciones administrativas, fiscales, contables y laborales que sean necesarias en virtud de la legislaci\u00f3n vigente.<\/li><\/ul>\n<\/div>\n\n<div class=\"wp-block body-block paragraph page-container\">\n<p class=\"wp-block-paragraph\">Puede revocar en cualquier momento su consentimiento remitiendo un escrito con el asunto \u201cBaja\u201d a info@nauivanow.com&nbsp;<a href=\"mailto:info@nauivanow.com\"><\/a>.<br>De acuerdo con la LSSICE, la Fundaci\u00f3 no realiza pr\u00e1cticas de correo basura, por lo tanto, no env\u00eda mensajes comerciales por e-mail que no hayan sido previamente solicitados o autorizados por el usuario. En consecuencia, en todas las comunicaciones que recibir\u00e1 de la Fundaci\u00f3 el usuario tiene la posibilidad de cancelar su consentimiento expreso para recibir nuestras comunicaciones.<\/p>\n<\/div>\n\n<div class=\"wp-block body-block paragraph page-container\">\n<p class=\"wp-block-paragraph\">Puede revocar en cualquier momento su consentimiento remitiendo un escrito con el asunto \u201cBaja\u201d a info@nauivanow.com.<br>De acuerdo con la LSSICE, la Fundaci\u00f3 no realiza pr\u00e1cticas de correo basura, por lo tanto, no env\u00eda mensajes electr\u00f3nicos comerciales que no hayan sido previamente solicitados o autorizados por el usuario. En consecuencia, en todas las comunicaciones que recibir\u00e1 de la Fundaci\u00f3 el usuario tiene la posibilidad de cancelar su consentimiento expreso para recibir nuestras comunicaciones.<\/p>\n<\/div>\n\n<div class=\"wp-block body-block paragraph page-container\">\n<p class=\"wp-block-paragraph\">No trataremos sus datos personales para ninguna otra finalidad de las descritas, excepto por obligaci\u00f3n legal o requerimiento judicial.<\/p>\n<\/div>\n\n<div class=\"wp-block body-block paragraph page-container\">\n<p class=\"wp-block-paragraph\">Sus datos se conservar\u00e1n mientras dure la relaci\u00f3n comercial con nosotros o ejercite su derecho de cancelaci\u00f3n, oposici\u00f3n o limitaci\u00f3n al tratamiento.<\/p>\n<\/div>\n\n<div class=\"wp-block body-block paragraph page-container\">\n<p class=\"wp-block-paragraph\"><strong>6.3. Legitimaci\u00f3n del <strong><strong>tratamiento<\/strong><\/strong><\/strong><br>La base legal para el tratamiento de los datos es su consentimiento otorgado para llevar a cabo las finalidades anteriormente descritas, que se solicitar\u00e1 en el momento de marcar la casilla correspondiente al recoger sus datos.<br>El no facilitar los datos personales solicitados o no aceptar la presente pol\u00edtica de protecci\u00f3n de datos supone la imposibilidad de subscribirse, registrarse o recibir informaci\u00f3n de nuestros productos y servicios.<br>En los casos en los que exista una previa relaci\u00f3n contractual entre las partes, la legitimaci\u00f3n por el desarrollo de las obligaciones administrativas, fiscales, contables y laborales que sean necesarias en virtud de la legislaci\u00f3n vigente ser\u00e1 la existencia previa de la relaci\u00f3n comercial establecida entre las partes.<\/p>\n<\/div>\n\n<div class=\"wp-block body-block paragraph page-container\">\n<p class=\"wp-block-paragraph\"><strong><strong>6.4. Medios de comunicaci\u00f3n<\/strong><br><\/strong>Se informa al usuario de que los medios habilitados por la Fundaci\u00f3 para comunicarse con usuarios y otros afectados son el correo electr\u00f3nico y el tel\u00e9fono corporativos.<\/p>\n<\/div>\n\n<div class=\"wp-block body-block paragraph page-container\">\n<p class=\"wp-block-paragraph\">Si remite informaci\u00f3n personal a trav\u00e9s de un medio de comunicaci\u00f3n distinto a los indicados en este apartado, la Fundaci\u00f3 quedar\u00e1 exenta de responsabilidad en relaci\u00f3n con las medidas de seguridad de las que disponga el medio en cuesti\u00f3n.<\/p>\n<\/div>\n\n<div class=\"wp-block body-block paragraph page-container\">\n<p class=\"wp-block-paragraph\"><strong>6.5. Destinatarios de cesiones o transferencias<\/strong><br>La Fundaci\u00f3 no realiza ninguna cesi\u00f3n o comunicaci\u00f3n de datos ni dentro ni fuera de la UE.<br>La informaci\u00f3n que nos proporcione a trav\u00e9s de este sitio web ser\u00e1 alojada en los servidores de la Fundaci\u00f3.<\/p>\n<\/div>\n\n<div class=\"wp-block body-block paragraph page-container\">\n<p class=\"wp-block-paragraph\"><strong>6.6. Derechos de las personas interesadas<strong><br><\/strong><\/strong>Como usuario-interesado, puede solicitar el ejercicio de los siguientes derechos ante la Fundaci\u00f3 enviando un mensaje electr\u00f3nico a info@nauivanow.com, indicando como asunto \u201cLOPD, Derechos ARCO\u201d y adjuntando fotocopia de su DNI, tal como indica la ley.<\/p>\n<\/div>\n\n<div class=\"wp-block body-block paragraph page-container\">\n<p class=\"wp-block-paragraph\"><strong>Derechos:<\/strong><\/p>\n<\/div>\n\n<div class=\"wp-block body-block list page-container\">\n<ul class=\"wp-block-list\"><li>Derecho de acceso: permite al interesado conocer y obtener informaci\u00f3n sobre sus datos de car\u00e1cter personal sometidos a tratamiento.<\/li><li>Derecho de rectificaci\u00f3n o supresi\u00f3n: permite corregir errores y modificar los datos que resulten ser inexactos o incompletos.<\/li><li>Derecho de cancelaci\u00f3n: permite que se supriman los datos que resulten ser inadecuados o excesivos.<\/li><li>Derecho de oposici\u00f3n: derecho del interesado a que no se lleve a cabo el tratamiento de sus datos de car\u00e1cter personal o se cese en el mismo.<\/li><li>Limitaci\u00f3n del tratamiento: comporta el marcado de los datos personales conservados, con el fin de limitar su futuro tratamiento.<\/li><li>Portabilidad de los datos: facilitaci\u00f3n de los datos objeto de tratamiento al interesado, a fin de que este pueda transmitirlos a otro responsable, sin impedimentos.<\/li><li>Derecho a no ser objeto de decisiones individuales automatizadas (incluida la elaboraci\u00f3n de perfiles): derecho a no ser objeto de una decisi\u00f3n basada en el tratamiento automatizado que produzca efectos o afecte significativamente.<\/li><\/ul>\n<\/div>\n\n<div class=\"wp-block body-block paragraph page-container\">\n<p class=\"wp-block-paragraph\">Como usuario, tiene derecho a retirar el consentimiento prestado en cualquier momento.<\/p>\n<\/div>\n\n<div class=\"wp-block body-block paragraph page-container\">\n<p class=\"wp-block-paragraph\">Puede ejercer los derechos que le otorga el Reglamento a:<br>Fundaci\u00f3 Privada Sagrera \u2013 Nau Ivanow<br>C. Hondures, 28-30, bajos<br>08027 Barcelona<br>Tel. 93 340 74 68 <br>info@nauivanow.com<\/p>\n<\/div>\n\n<div class=\"wp-block body-block paragraph page-container\">\n<p class=\"wp-block-paragraph\">Tambi\u00e9n tiene derecho a presentar una reclamaci\u00f3n ante la autoridad de control si considera que pueden haberse visto vulnerados sus derechos con relaci\u00f3n a la protecci\u00f3n de sus datos (agpd.es).<\/p>\n<\/div>\n\n<div class=\"wp-block body-block paragraph page-container\">\n<p class=\"wp-block-paragraph\"><strong>6.7. Informaci\u00f3n que recogemos<\/strong><br>Obtenemos mediante formulario de suscripci\u00f3n la informaci\u00f3n m\u00ednima e indispensable. En el formulario se facilitar\u00e1n los siguientes datos: e-mail, nombre, apellidos y tel\u00e9fono.<br>Los datos personales que nos facilite se conservan mientras haya un inter\u00e9s mutuo para mantener la finalidad del tratamiento, o mientras haya que conservarlas por motivo de obligaciones legales. Cuando la conservaci\u00f3n ya no sea necesaria, se suprimen con las medidas de seguridad adecuadas para garantizar la seudonimizaci\u00f3n o la destrucci\u00f3n total de los datos.<\/p>\n<\/div>\n\n<div class=\"wp-block body-block paragraph page-container\">\n<p class=\"wp-block-paragraph\"><strong>6.8. Redes sociales<\/strong><br>Le informamos que la Fundaci\u00f3 puede tener presencia en redes sociales. El tratamiento de los datos que se lleve a cabo de las personas que se hagan seguidoras en las redes sociales (y\/o realicen cualquier v\u00ednculo o acci\u00f3n de conexi\u00f3n a trav\u00e9s de las redes sociales) de las p\u00e1ginas oficiales de la Fundaci\u00f3 se regir\u00e1 por este apartado, as\u00ed como por aquellas condiciones de uso, pol\u00edticas de privacidad y normativas de acceso que pertenezcan en la red social que proceda en cada caso y aceptadas previamente por el usuario.<\/p>\n<\/div>\n\n<div class=\"wp-block body-block paragraph page-container\">\n<p class=\"wp-block-paragraph\">Queda prohibida la publicaci\u00f3n de contenidos:<\/p>\n<\/div>\n\n<div class=\"wp-block body-block list page-container\">\n<ul class=\"wp-block-list\"><li>Que sean presuntamente il\u00edcitos por la normativa nacional, comunitaria o internacional o que realicen actividades presuntamente il\u00edcitas o contravengan los principios de la buena fe.<\/li><li>Que atenten contra los derechos fundamentales de las personas.<\/li><li>Y en general que contravengan los principios de legalidad, honradez, responsabilidad, protecci\u00f3n de la dignidad humana, protecci\u00f3n de menores, protecci\u00f3n del orden p\u00fablico, la protecci\u00f3n de la vida privada, la protecci\u00f3n del consumidor y los derechos de propiedad intelectual e industrial.<\/li><\/ul>\n<\/div>\n\n<div class=\"wp-block body-block paragraph page-container\">\n<p class=\"wp-block-paragraph\">As\u00ed mismo, la Fundaci\u00f3 se reserva la potestad de retirar, sin previo aviso, del sitio web o de la red social corporativa aquellos contenidos que se consideren inapropiados.<\/p>\n<\/div>\n\n<div class=\"wp-block body-block paragraph page-container\">\n<p class=\"wp-block-paragraph\">En todo caso, si remite informaci\u00f3n personal a trav\u00e9s de la red social, la Fundaci\u00f3 quedar\u00e1 exenta de responsabilidad en relaci\u00f3n con las medidas de seguridad aplicables a la presente plataforma, habiendo el usuario en caso de querer conocerlas, consultar las correspondientes condiciones particulares de la red en cuesti\u00f3n.<\/p>\n<\/div>\n\n<div class=\"wp-block body-block paragraph page-container\">\n<p class=\"wp-block-paragraph\"><strong>6.9 Medidas de seguridad<br><\/strong>Los datos que nos facilite se tratar\u00e1n de manera confidencial. La Fundaci\u00f3 ha adoptado todas las medidas t\u00e9cnicas y organizativas y todos los niveles de protecci\u00f3n necesarios para garantizar la seguridad en el tratamiento de los datos y evitar su alteraci\u00f3n, p\u00e9rdida, robo, tratamiento o acceso no autorizado, seg\u00fan el estado de la tecnolog\u00eda y naturaleza de los datos almacenados. As\u00ed mismo, se garantiza tambi\u00e9n que el tratamiento y registro en ficheros, programas, sistemas o equipos, locales y centros cumplen con los requisitos y condiciones de integridad y seguridad establecidos en la normativa vigente.<\/p>\n<\/div>\n\n<div class=\"wp-block body-block paragraph page-container\">\n<p class=\"wp-block-paragraph\"><strong>6.10 Cambios en la presente pol\u00edtica de privacidad<br><\/strong>Fundaci\u00f3 Privada Sagrera \u2013 Nau Ivanow se reserva el derecho a modificar la presente pol\u00edtica para adaptarla a novedades legislativas o jurisprudenciales.<\/p>\n<\/div>\n\n<div class=\"wp-block body-block paragraph page-container\">\n<p class=\"wp-block-paragraph\"><br><strong>7. LEGISLACI\u00d3N APLICABLE Y JURISDICCI\u00d3N<br><\/strong><br>La presente Nota legal queda sujeta a la legislaci\u00f3n espa\u00f1ola vigente aplicable. Para la resoluci\u00f3n de cualquier conflicto o litigio que pudiera derivarse del acceso a esta p\u00e1gina web, los usuarios y la Fundaci\u00f3 se someten expresamente a los juzgados y tribunales de la ciudad de Barcelona, con renuncia expresa a cualquier otro fuero que les pudiera corresponder.<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>1. INFORMACI\u00d3N GENERAL La Fundaci\u00f3 Privada Sagrera es una fundaci\u00f3n privada constituida el 12 de enero de 2006 que tiene el objeto de facilitar la creaci\u00f3n, la difusi\u00f3n y la capacitaci\u00f3n de los profesionales de la cultura y las artes esc\u00e9nicas, en especial del teatro, con una atenci\u00f3n especial hacia los nuevos creadores. La Fundaci\u00f3&nbsp; <a href=\"https:\/\/nauivanow.com\/es\/nota-legal\/\">&hellip; Read more <i class=\"glyphicon glyphicon-arrow-right\"><\/i><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":99,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_uag_custom_page_level_css":"","footnotes":""},"class_list":["post-1998","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nota legal - Nau Ivanow<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nauivanow.com\/es\/nota-legal\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nota legal - Nau Ivanow\" \/>\n<meta property=\"og:description\" content=\"1. INFORMACI\u00d3N GENERAL La Fundaci\u00f3 Privada Sagrera es una fundaci\u00f3n privada constituida el 12 de enero de 2006 que tiene el objeto de facilitar la creaci\u00f3n, la difusi\u00f3n y la capacitaci\u00f3n de los profesionales de la cultura y las artes esc\u00e9nicas, en especial del teatro, con una atenci\u00f3n especial hacia los nuevos creadores. La Fundaci\u00f3&nbsp; &hellip; Read more\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nauivanow.com\/es\/nota-legal\/\" \/>\n<meta property=\"og:site_name\" content=\"Nau Ivanow\" \/>\n<meta property=\"article:modified_time\" content=\"2021-05-10T10:10:37+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"13 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nauivanow.com\\\/es\\\/nota-legal\\\/\",\"url\":\"https:\\\/\\\/nauivanow.com\\\/es\\\/nota-legal\\\/\",\"name\":\"Nota legal - Nau Ivanow\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nauivanow.com\\\/es\\\/#website\"},\"datePublished\":\"2020-11-06T15:49:13+00:00\",\"dateModified\":\"2021-05-10T10:10:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nauivanow.com\\\/es\\\/nota-legal\\\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nauivanow.com\\\/es\\\/nota-legal\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nauivanow.com\\\/es\\\/nota-legal\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nauivanow.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nota legal\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nauivanow.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/nauivanow.com\\\/es\\\/\",\"name\":\"Nau Ivanow\",\"description\":\"Espai de resid\u00e8ncies d\u2019arts esc\u00e8niques\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nauivanow.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nota legal - Nau Ivanow","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nauivanow.com\/es\/nota-legal\/","og_locale":"es_ES","og_type":"article","og_title":"Nota legal - Nau Ivanow","og_description":"1. INFORMACI\u00d3N GENERAL La Fundaci\u00f3 Privada Sagrera es una fundaci\u00f3n privada constituida el 12 de enero de 2006 que tiene el objeto de facilitar la creaci\u00f3n, la difusi\u00f3n y la capacitaci\u00f3n de los profesionales de la cultura y las artes esc\u00e9nicas, en especial del teatro, con una atenci\u00f3n especial hacia los nuevos creadores. La Fundaci\u00f3&nbsp; &hellip; Read more","og_url":"https:\/\/nauivanow.com\/es\/nota-legal\/","og_site_name":"Nau Ivanow","article_modified_time":"2021-05-10T10:10:37+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"13 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nauivanow.com\/es\/nota-legal\/","url":"https:\/\/nauivanow.com\/es\/nota-legal\/","name":"Nota legal - Nau Ivanow","isPartOf":{"@id":"https:\/\/nauivanow.com\/es\/#website"},"datePublished":"2020-11-06T15:49:13+00:00","dateModified":"2021-05-10T10:10:37+00:00","breadcrumb":{"@id":"https:\/\/nauivanow.com\/es\/nota-legal\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nauivanow.com\/es\/nota-legal\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/nauivanow.com\/es\/nota-legal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nauivanow.com\/es\/"},{"@type":"ListItem","position":2,"name":"Nota legal"}]},{"@type":"WebSite","@id":"https:\/\/nauivanow.com\/es\/#website","url":"https:\/\/nauivanow.com\/es\/","name":"Nau Ivanow","description":"Espai de resid\u00e8ncies d\u2019arts esc\u00e8niques","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nauivanow.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"}]}},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false},"uagb_author_info":{"display_name":"Marc","author_link":"https:\/\/nauivanow.com\/es\/author\/marc\/"},"uagb_comment_info":0,"uagb_excerpt":"1. INFORMACI\u00d3N GENERAL La Fundaci\u00f3 Privada Sagrera es una fundaci\u00f3n privada constituida el 12 de enero de 2006 que tiene el objeto de facilitar la creaci\u00f3n, la difusi\u00f3n y la capacitaci\u00f3n de los profesionales de la cultura y las artes esc\u00e9nicas, en especial del teatro, con una atenci\u00f3n especial hacia los nuevos creadores. La Fundaci\u00f3&nbsp;&hellip;","_links":{"self":[{"href":"https:\/\/nauivanow.com\/es\/wp-json\/wp\/v2\/pages\/1998","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nauivanow.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/nauivanow.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/nauivanow.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nauivanow.com\/es\/wp-json\/wp\/v2\/comments?post=1998"}],"version-history":[{"count":0,"href":"https:\/\/nauivanow.com\/es\/wp-json\/wp\/v2\/pages\/1998\/revisions"}],"wp:attachment":[{"href":"https:\/\/nauivanow.com\/es\/wp-json\/wp\/v2\/media?parent=1998"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}