{"id":4934,"date":"2020-09-16T00:00:00","date_gmt":"2020-09-15T23:00:00","guid":{"rendered":"https:\/\/nauivanow.com\/en-obert\/medium-chile-estalla-a-la-distancia-de-la-cia-teatro-apatrida\/"},"modified":"2020-09-16T00:00:00","modified_gmt":"2020-09-15T23:00:00","slug":"medium-chile-estalla-a-la-distancia-de-la-cia-teatro-apatrida","status":"publish","type":"event","link":"https:\/\/nauivanow.com\/es\/en-obert\/medium-chile-estalla-a-la-distancia-de-la-cia-teatro-apatrida\/","title":{"rendered":"&#8216;M\u00e9dium, Chile estalla a la distancia&#8217;\u00a0de la cia\u00a0Teatro Ap\u00e1trida"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-18090\" src=\"https:\/\/nauivanow.com\/wp-content\/uploads\/2020\/03\/2-1-1024x678.jpg\" alt=\"\" width=\"1024\" height=\"678\" \/><\/p>\n<p>Desde la Nau Ivanow nos gusta establecer puentes y conexiones con compa\u00f1\u00edas de todo el mundo. A principios de este a\u00f1o, la compa\u00f1\u00eda chilena <strong>Teatro ap\u00e1trida<\/strong> realiz\u00f3 una <strong>residencia de creaci\u00f3n<\/strong> que finalizar\u00eda con una muestra abierta de este proceso. El confinamiento lo cancel\u00f3, pero finalmente los d\u00edas <strong>30 de septiembre, 1 y 2 de octubre<\/strong>\u00a0se podr\u00e1 estrenar la obra <strong>&#8216;M\u00e9dium, Chile estalla a la distancia&#8217;.<\/strong><\/p>\n<p>Seis creadores chilenos venidos en distintas disciplinas del teatro se re\u00fanen para intentar reconstituir una parte del estallido social en Chile, desde la distancia f\u00edsica con su tierra de origen y la imposibilidad de poder vivir en carne propia una revoluci\u00f3n al otro lado de la cordillera para preguntarnos si es posible encontrar un \u00abM\u00e9dium\u00bb que nos cuente lo que all\u00ed sucede.<\/p>\n<p>El equipo durante estos meses recopil\u00f3 relatos y testimonios de testigos directos, trozos de documentaci\u00f3n period\u00edstica, relatos, fotograf\u00edas, audios personales de amigos y familiares, sumado a la intenci\u00f3n de escribir acerca de la distancia y dar visibilidad a una crisis social que puede ser vista como una met\u00e1fora de una realidad pol\u00edtica de muchos pa\u00edses.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-19202\" src=\"https:\/\/nauivanow.com\/wp-content\/uploads\/2020\/09\/1-1-1024x678.jpg\" alt=\"\" width=\"1024\" height=\"678\" \/>Omar Moran Reyes, actor profesor y director teatral Chileno, se desempe\u00f1a como profesor de interpretaci\u00f3n en distintos centros de estudios y universidades de Chile. Ha dirigido una decena de montajes de distintos autores contempor\u00e1neos, en los que destaca una predilecci\u00f3n por dramaturgias verborreicas y delirantes como Spregelburd, Bernhard y Cocteau. En 2013 viaja a Valencia becado por Iberescena para el proyecto Perro Suelto, a partir de la recopilaci\u00f3n de testimonio de migrantes y bajo esta misma l\u00f3gica en Marzo de 2020 realiza el Proyecto M\u00e9dium, a partir de la recopilaci\u00f3n de testimonios de testigos de la revoluci\u00f3n social de Chile. Actualmente estudia un M\u00e1ster en Estudios Teatrales en Barcelona.<\/p>\n<h5><\/h5>\n<h5><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-19201\" src=\"https:\/\/nauivanow.com\/wp-content\/uploads\/2020\/09\/4-1-1024x573.jpg\" alt=\"\" width=\"1024\" height=\"573\" \/>FUNCIONES<\/h5>\n<p>Mi\u00e9rcoles 30 de septiembre, 1 y 2 de octubre a las 20.30h<\/p>\n<p><strong>NUEVA FUNCI\u00d3N!<\/strong> S\u00e1bado 3 de octubre a las 20.30h<\/p>\n<p><strong>ENTRADAS: 12\u20ac<\/strong><\/p>\n<p><strong><a class=\"button\" href=\"https:\/\/entradium.com\/events\/vuelve-medium-de-la-cia-teatro-apatrida\">COMPRA AQU\u00cd TU ENTRADA<\/a><\/strong><\/p>\n<h5>INFORMACI\u00d3N<\/h5>\n<p>Idioma:\u00a0<strong>castellano<br \/>\n<\/strong>Duraci\u00f3n:<b>\u00a075 minutos<\/b><\/p>\n<p>&nbsp;<\/p>\n<h5>FICHA T\u00c9CNICA<\/h5>\n<p>Compa\u00f1\u00eda:\u00a0<strong>Teatro Ap\u00e1trida<\/strong><br \/>\nPuesta en Escena:\u00a0<strong>Omar Mor\u00e1n Reyes<\/strong><br \/>\nDramaturgia:\u00a0<strong>Omar Mor\u00e1n, compa\u00f1\u00eda Teatro Ap\u00e1trida y relatos testimoniales<\/strong><br \/>\nInt\u00e9rpretes:\u00a0<strong>Andrea Paz, Gabriel D\u00edaz, Daniela Garc\u00eda, Gonzalo Dalgalarrando<\/strong><br \/>\nM\u00fasica:\u00a0<strong>Alejandro Miranda<\/strong><br \/>\nProducci\u00f3n:\u00a0<strong>Teatro Ap\u00e1trida<\/strong><br \/>\nEspacio y Vestuarios:\u00a0<strong>Teatro Ap\u00e1trida<\/strong><br \/>\nIluminaci\u00f3n:\u00a0<strong>Josefina Cifuentes<\/strong><\/p>\n","protected":false},"featured_media":0,"template":"","event_type":[33],"class_list":["post-4934","event","type-event","status-publish","hentry","event_type-actos-abiertos"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>&#039;M\u00e9dium, Chile estalla a la distancia&#039;\u00a0de la cia\u00a0Teatro Ap\u00e1trida - Nau Ivanow<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nauivanow.com\/es\/en-obert\/medium-chile-estalla-a-la-distancia-de-la-cia-teatro-apatrida\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&#039;M\u00e9dium, Chile estalla a la distancia&#039;\u00a0de la cia\u00a0Teatro Ap\u00e1trida - Nau Ivanow\" \/>\n<meta property=\"og:description\" content=\"Desde la Nau Ivanow nos gusta establecer puentes y conexiones con compa\u00f1\u00edas de todo el mundo. A principios de este a\u00f1o, la compa\u00f1\u00eda chilena Teatro ap\u00e1trida realiz\u00f3 una residencia de creaci\u00f3n que finalizar\u00eda con una muestra abierta de este proceso. El confinamiento lo cancel\u00f3, pero finalmente los d\u00edas 30 de septiembre, 1 y 2 de&nbsp; &hellip; Read more\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nauivanow.com\/es\/en-obert\/medium-chile-estalla-a-la-distancia-de-la-cia-teatro-apatrida\/\" \/>\n<meta property=\"og:site_name\" content=\"Nau Ivanow\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nauivanow.com\/wp-content\/uploads\/2020\/03\/2-1-1024x678.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nauivanow.com\\\/es\\\/en-obert\\\/medium-chile-estalla-a-la-distancia-de-la-cia-teatro-apatrida\\\/\",\"url\":\"https:\\\/\\\/nauivanow.com\\\/es\\\/en-obert\\\/medium-chile-estalla-a-la-distancia-de-la-cia-teatro-apatrida\\\/\",\"name\":\"'M\u00e9dium, Chile estalla a la distancia'\u00a0de la cia\u00a0Teatro Ap\u00e1trida - Nau Ivanow\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nauivanow.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/nauivanow.com\\\/es\\\/en-obert\\\/medium-chile-estalla-a-la-distancia-de-la-cia-teatro-apatrida\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/nauivanow.com\\\/es\\\/en-obert\\\/medium-chile-estalla-a-la-distancia-de-la-cia-teatro-apatrida\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nauivanow.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/2-1-1024x678.jpg\",\"datePublished\":\"2020-09-15T23:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nauivanow.com\\\/es\\\/en-obert\\\/medium-chile-estalla-a-la-distancia-de-la-cia-teatro-apatrida\\\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nauivanow.com\\\/es\\\/en-obert\\\/medium-chile-estalla-a-la-distancia-de-la-cia-teatro-apatrida\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/nauivanow.com\\\/es\\\/en-obert\\\/medium-chile-estalla-a-la-distancia-de-la-cia-teatro-apatrida\\\/#primaryimage\",\"url\":\"https:\\\/\\\/nauivanow.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/2-1-1024x678.jpg\",\"contentUrl\":\"https:\\\/\\\/nauivanow.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/2-1-1024x678.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nauivanow.com\\\/es\\\/en-obert\\\/medium-chile-estalla-a-la-distancia-de-la-cia-teatro-apatrida\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nauivanow.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&#8216;M\u00e9dium, Chile estalla a la distancia&#8217;\u00a0de la cia\u00a0Teatro Ap\u00e1trida\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nauivanow.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/nauivanow.com\\\/es\\\/\",\"name\":\"Nau Ivanow\",\"description\":\"Espai de resid\u00e8ncies d\u2019arts esc\u00e8niques\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nauivanow.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"'M\u00e9dium, Chile estalla a la distancia'\u00a0de la cia\u00a0Teatro Ap\u00e1trida - Nau Ivanow","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nauivanow.com\/es\/en-obert\/medium-chile-estalla-a-la-distancia-de-la-cia-teatro-apatrida\/","og_locale":"es_ES","og_type":"article","og_title":"'M\u00e9dium, Chile estalla a la distancia'\u00a0de la cia\u00a0Teatro Ap\u00e1trida - Nau Ivanow","og_description":"Desde la Nau Ivanow nos gusta establecer puentes y conexiones con compa\u00f1\u00edas de todo el mundo. A principios de este a\u00f1o, la compa\u00f1\u00eda chilena Teatro ap\u00e1trida realiz\u00f3 una residencia de creaci\u00f3n que finalizar\u00eda con una muestra abierta de este proceso. El confinamiento lo cancel\u00f3, pero finalmente los d\u00edas 30 de septiembre, 1 y 2 de&nbsp; &hellip; Read more","og_url":"https:\/\/nauivanow.com\/es\/en-obert\/medium-chile-estalla-a-la-distancia-de-la-cia-teatro-apatrida\/","og_site_name":"Nau Ivanow","og_image":[{"url":"https:\/\/nauivanow.com\/wp-content\/uploads\/2020\/03\/2-1-1024x678.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nauivanow.com\/es\/en-obert\/medium-chile-estalla-a-la-distancia-de-la-cia-teatro-apatrida\/","url":"https:\/\/nauivanow.com\/es\/en-obert\/medium-chile-estalla-a-la-distancia-de-la-cia-teatro-apatrida\/","name":"'M\u00e9dium, Chile estalla a la distancia'\u00a0de la cia\u00a0Teatro Ap\u00e1trida - Nau Ivanow","isPartOf":{"@id":"https:\/\/nauivanow.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nauivanow.com\/es\/en-obert\/medium-chile-estalla-a-la-distancia-de-la-cia-teatro-apatrida\/#primaryimage"},"image":{"@id":"https:\/\/nauivanow.com\/es\/en-obert\/medium-chile-estalla-a-la-distancia-de-la-cia-teatro-apatrida\/#primaryimage"},"thumbnailUrl":"https:\/\/nauivanow.com\/wp-content\/uploads\/2020\/03\/2-1-1024x678.jpg","datePublished":"2020-09-15T23:00:00+00:00","breadcrumb":{"@id":"https:\/\/nauivanow.com\/es\/en-obert\/medium-chile-estalla-a-la-distancia-de-la-cia-teatro-apatrida\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nauivanow.com\/es\/en-obert\/medium-chile-estalla-a-la-distancia-de-la-cia-teatro-apatrida\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/nauivanow.com\/es\/en-obert\/medium-chile-estalla-a-la-distancia-de-la-cia-teatro-apatrida\/#primaryimage","url":"https:\/\/nauivanow.com\/wp-content\/uploads\/2020\/03\/2-1-1024x678.jpg","contentUrl":"https:\/\/nauivanow.com\/wp-content\/uploads\/2020\/03\/2-1-1024x678.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/nauivanow.com\/es\/en-obert\/medium-chile-estalla-a-la-distancia-de-la-cia-teatro-apatrida\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nauivanow.com\/es\/"},{"@type":"ListItem","position":2,"name":"&#8216;M\u00e9dium, Chile estalla a la distancia&#8217;\u00a0de la cia\u00a0Teatro Ap\u00e1trida"}]},{"@type":"WebSite","@id":"https:\/\/nauivanow.com\/es\/#website","url":"https:\/\/nauivanow.com\/es\/","name":"Nau Ivanow","description":"Espai de resid\u00e8ncies d\u2019arts esc\u00e8niques","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nauivanow.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"}]}},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false},"uagb_author_info":{"display_name":"Marc","author_link":"https:\/\/nauivanow.com\/es\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"Desde la Nau Ivanow nos gusta establecer puentes y conexiones con compa\u00f1\u00edas de todo el mundo. A principios de este a\u00f1o, la compa\u00f1\u00eda chilena Teatro ap\u00e1trida realiz\u00f3 una residencia de creaci\u00f3n que finalizar\u00eda con una muestra abierta de este proceso. El confinamiento lo cancel\u00f3, pero finalmente los d\u00edas 30 de septiembre, 1 y 2 de&nbsp;&hellip;","_links":{"self":[{"href":"https:\/\/nauivanow.com\/es\/wp-json\/wp\/v2\/event\/4934","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nauivanow.com\/es\/wp-json\/wp\/v2\/event"}],"about":[{"href":"https:\/\/nauivanow.com\/es\/wp-json\/wp\/v2\/types\/event"}],"wp:attachment":[{"href":"https:\/\/nauivanow.com\/es\/wp-json\/wp\/v2\/media?parent=4934"}],"wp:term":[{"taxonomy":"event_type","embeddable":true,"href":"https:\/\/nauivanow.com\/es\/wp-json\/wp\/v2\/event_type?post=4934"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}